{"id":77981,"date":"2024-10-25T12:49:51","date_gmt":"2024-10-25T18:49:51","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/salero-3\/"},"modified":"2024-12-04T17:45:50","modified_gmt":"2024-12-04T23:45:50","slug":"salero-3","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/salero-3\/","title":{"rendered":"Salero."},"content":{"rendered":"<section class=\"extracto\"><b>Productor Autor:<\/b> Productor No Identificado.<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> Pa\u00eds desconocido.<\/p>\n<p><b>Procedencia:<\/b> MODO, Museo del Objeto del Objeto.<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> 2.80<\/p>\n<p><b>Largo Alto:<\/b> 4.30<\/p>\n<p><b>Profundidad:<\/b> 2.80<\/p>\n<p><b>Material predominante:<\/b> Pl\u00e1stico<\/p>\n<p><b>Colecci\u00f3n:<\/b> Alimentaci\u00f3n<\/p>\n<p><b>Categor\u00eda:<\/b> Utensilios de Cocina y Comedor<\/p>\n<p><b>ID Inventario:<\/b> 120872<\/p>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Productor No Identificado. A\u00f1o: S\/F Pa\u00eds: Pa\u00eds desconocido. Procedencia: MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":80290,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2582,2586],"anho":[2713],"pais":[2717],"class_list":["post-77981","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-alimentacion","cat-objetos-utensilios-de-cocina-y-comedor","anho-s-f","pais-pais-desconocido"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/77981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=77981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/80290"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=77981"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=77981"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=77981"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=77981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}