{"id":63704,"date":"2024-09-18T10:15:32","date_gmt":"2024-09-18T16:15:32","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/cajitas-con-5-hojas-extra-delgadas\/"},"modified":"2024-12-04T17:44:11","modified_gmt":"2024-12-04T23:44:11","slug":"cajitas-con-5-hojas-extra-delgadas","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/cajitas-con-5-hojas-extra-delgadas\/","title":{"rendered":"Cajitas Con 5 Hojas Extra Delgadas."},"content":{"rendered":"<section class=\"extracto\"><b>Productor Autor:<\/b> Pegaso.<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> M\u00e9xico.<\/p>\n<p><b>Procedencia:<\/b> MODO, Museo del Objeto del Objeto.<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> 5.4<\/p>\n<p><b>Largo Alto:<\/b> 16.5<\/p>\n<p><b>Profundidad:<\/b> 2.8<\/p>\n<p><b>Material predominante:<\/b> Cart\u00f3n<\/p>\n<p><b>Colecci\u00f3n:<\/b> Salud<\/p>\n<p><b>Categor\u00eda:<\/b> Higiene Personal<\/p>\n<p><b>ID Inventario:<\/b> 141056<\/p>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Pegaso A\u00f1o: S\/F Pa\u00eds: M\u00e9xico Procedencia: MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":63705,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2646,2645],"anho":[2713],"pais":[2714],"class_list":["post-63704","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-higiene-personal","cat-objetos-salud","anho-s-f","pais-mexico"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/63704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=63704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/63705"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=63704"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=63704"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=63704"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=63704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}