{"id":63421,"date":"2024-09-18T10:13:11","date_gmt":"2024-09-18T16:13:11","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/estuche-para-rasurar-miniatura-emir\/"},"modified":"2024-12-04T17:44:05","modified_gmt":"2024-12-04T23:44:05","slug":"estuche-para-rasurar-miniatura-emir","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/estuche-para-rasurar-miniatura-emir\/","title":{"rendered":"Estuche Para Rasurar Miniatura. Emir."},"content":{"rendered":"<section class=\"extracto\">\n<p><b>Productor Autor:<\/b> Emir.<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> Pa\u00eds desconocido.<\/p>\n<p><b>Procedencia:<\/b> MODO, Museo del Objeto del Objeto.<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> 14.2<\/p>\n<p><b>Largo Alto:<\/b> 4.8<\/p>\n<p>        <b>Profundidad:<\/b> 1.1<\/p>\n<p><b>Material predominante:<\/b> Textil<\/p>\n<p><b>Colecci\u00f3n:<\/b> Salud<\/p>\n<p><b>Categor\u00eda:<\/b> Higiene Personal<\/p>\n<p><b>ID Inventario:<\/b> 91780<\/p>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Emir. A\u00f1o: S\/F Pa\u00eds: Pa\u00eds desconocido Procedencia: MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":63422,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2646,2645],"anho":[2713],"pais":[2717],"class_list":["post-63421","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-higiene-personal","cat-objetos-salud","anho-s-f","pais-pais-desconocido"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/63421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=63421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/63422"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=63421"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=63421"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=63421"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=63421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}