{"id":55583,"date":"2024-09-11T16:31:57","date_gmt":"2024-09-11T22:31:57","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/fotografia-el-palacio-nacional-en-la-decena-tragica\/"},"modified":"2024-12-04T17:41:21","modified_gmt":"2024-12-04T23:41:21","slug":"fotografia-el-palacio-nacional-en-la-decena-tragica","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/fotografia-el-palacio-nacional-en-la-decena-tragica\/","title":{"rendered":"Fotograf\u00eda. El Palacio Nacional En La Decena Tr\u00e1gica."},"content":{"rendered":"<section class=\"extracto\">\n<p><b>Productor Autor:<\/b> Productor No Identificado.<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> Pa\u00eds desconocido<\/p>\n<p><b>Procedencia:<\/b> MODO, Museo del Objeto del Objeto.<\/p>\n<p>\u00a0<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> 14<\/p>\n<p><b>Largo Alto:<\/b> 9.1<\/p>\n<p><b>Profundidad:<\/b> <\/p>\n<p><b>Material predominante:<\/b> Papel<\/p>\n<p>\u00a0<\/p>\n<p><b>Colecci\u00f3n:<\/b> Gobierno<\/p>\n<p><b>Categor\u00eda:<\/b> Revoluci\u00f3n Mexicana<\/p>\n<p><b>ID Inventario:<\/b> 58041<\/p>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Productor No Identificado. A\u00f1o: S\/F Pa\u00eds: Pa\u00eds desconocido Procedencia: MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":55584,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2617,2625],"anho":[2713],"pais":[2717],"class_list":["post-55583","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-gobierno","cat-objetos-revolucion-mexicana","anho-s-f","pais-pais-desconocido"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/55583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=55583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/55584"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=55583"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=55583"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=55583"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=55583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}