{"id":52583,"date":"2024-09-11T13:49:55","date_gmt":"2024-09-11T19:49:55","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/benson-hedges-100s-cajetilla-de-cigarros\/"},"modified":"2024-12-04T17:40:20","modified_gmt":"2024-12-04T23:40:20","slug":"benson-hedges-100s-cajetilla-de-cigarros","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/benson-hedges-100s-cajetilla-de-cigarros\/","title":{"rendered":"Benson &#038; Hedges 100\u2019S.  Cajetilla De Cigarros."},"content":{"rendered":"<section class=\"extracto\">\n<p><b>Productor Autor:<\/b> Benson &#038; Hedges, Richmond. Va.<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> Estados Unidos<\/p>\n<p><b>Procedencia:<\/b> Obsequio de Luis Estrada. MODO, Museo del Objeto del Objeto.<\/p>\n<p>\u00a0<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> <\/p>\n<p><b>Largo Alto:<\/b> <\/p>\n<p><b>Profundidad:<\/b> <\/p>\n<p><b>Material predominante:<\/b> Cart\u00f3n<\/p>\n<p>\u00a0<\/p>\n<p><b>Colecci\u00f3n:<\/b> Entretenimiento<\/p>\n<p><b>Categor\u00eda:<\/b> Tabaco<\/p>\n<p><b>ID Inventario:<\/b> 30200<\/p>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Benson &#038; Hedges, Richmond. Va. A\u00f1o: S\/F Pa\u00eds: Estados Unidos Procedencia: Obsequio de Luis Estrada. MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":52584,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2607,2615],"anho":[2713],"pais":[2719],"class_list":["post-52583","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-entretenimiento","cat-objetos-tabaco","anho-s-f","pais-estados-unidos"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/52583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=52583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/52584"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=52583"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=52583"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=52583"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=52583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}