{"id":43453,"date":"2024-09-09T16:17:28","date_gmt":"2024-09-09T22:17:28","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/fumisteria-canamer-pisapapel-promocional\/"},"modified":"2024-12-04T17:37:23","modified_gmt":"2024-12-04T23:37:23","slug":"fumisteria-canamer-pisapapel-promocional","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/fumisteria-canamer-pisapapel-promocional\/","title":{"rendered":"Fumisteria: Ca\u00f1amer. Pisapapel Promocional"},"content":{"rendered":"<section class=\"extracto\">\n<p><b>Productor Autor:<\/b> Productor No Identificado.<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> Pa\u00eds desconocido<\/p>\n<p><b>Procedencia:<\/b> MODO, Museo del Objeto del Objeto.<\/p>\n<p>\u00a0<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> 10.4<\/p>\n<p><b>Largo Alto:<\/b> 6.5<\/p>\n<p><b>Profundidad:<\/b> 2.7<\/p>\n<p><b>Material predominante:<\/b> Vidrio<\/p>\n<p>\u00a0<\/p>\n<p><b>Colecci\u00f3n:<\/b> Comercio<\/p>\n<p><b>Categor\u00eda:<\/b> Publicidad<\/p>\n<p><b>ID Inventario:<\/b> 63032<\/p>\n<\/section>\n<p>\u00a0<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Productor No Identificado. A\u00f1o: S\/F Pa\u00eds: Pa\u00eds desconocido Procedencia: MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":43454,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2592,2596],"anho":[2713],"pais":[2717],"class_list":["post-43453","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-comercio","cat-objetos-publicidad","anho-s-f","pais-pais-desconocido"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/43453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=43453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/43454"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=43453"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=43453"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=43453"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=43453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}