{"id":43135,"date":"2024-09-09T16:14:22","date_gmt":"2024-09-09T22:14:22","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/salvitae-folleto-publicitario-de-solvente-del-acido-urico\/"},"modified":"2024-12-04T17:37:16","modified_gmt":"2024-12-04T23:37:16","slug":"salvitae-folleto-publicitario-de-solvente-del-acido-urico","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/salvitae-folleto-publicitario-de-solvente-del-acido-urico\/","title":{"rendered":"Salvitae. Folleto."},"content":{"rendered":"<section class=\"extracto\">\n<p><b>Productor Autor:<\/b> Productor No Identificado.<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> Pa\u00eds desconocido.<\/p>\n<p><b>Procedencia:<\/b> MODO, Museo del Objeto del Objeto.<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> 14.2<\/p>\n<p><b>Largo Alto:<\/b> 9<\/p>\n<p>        <b>Profundidad:<\/b> <\/p>\n<p><b>Material predominante:<\/b> Papel<\/p>\n<p><b>Colecci\u00f3n:<\/b> Salud<\/p>\n<p><b>Categor\u00eda:<\/b> Medicina<\/p>\n<p><b>ID Inventario:<\/b> 31248<\/p>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Productor No Identificado. A\u00f1o: S\/F Pa\u00eds: Pa\u00eds desconocido. Procedencia: MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":43136,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2592,2596],"anho":[2713],"pais":[2717],"class_list":["post-43135","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-comercio","cat-objetos-publicidad","anho-s-f","pais-pais-desconocido"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/43135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=43135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/43136"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=43135"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=43135"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=43135"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=43135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}