{"id":42505,"date":"2024-09-09T16:02:27","date_gmt":"2024-09-09T22:02:27","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/flor-fina-etiqueta\/"},"modified":"2024-12-04T17:37:04","modified_gmt":"2024-12-04T23:37:04","slug":"flor-fina-etiqueta","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/flor-fina-etiqueta\/","title":{"rendered":"Flor Fina. Etiqueta."},"content":{"rendered":"<section class=\"extracto\">\n<p><b>Productor Autor:<\/b> Productor No Identificado.<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> Pa\u00eds desconocido<\/p>\n<p><b>Procedencia:<\/b> MODO, Museo del Objeto del Objeto.<\/p>\n<p>\u00a0<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> 14.9<\/p>\n<p><b>Largo Alto:<\/b> 2.1<\/p>\n<p><b>Profundidad:<\/b> <\/p>\n<p><b>Material predominante:<\/b> Papel<\/p>\n<p>\u00a0<\/p>\n<p><b>Colecci\u00f3n:<\/b> Comercio<\/p>\n<p><b>Categor\u00eda:<\/b> Embalaje<\/p>\n<p><b>ID Inventario:<\/b> 66991<\/p>\n<\/section>\n<p>\u00a0<\/section>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Productor No Identificado. A\u00f1o: S\/F Pa\u00eds: Pa\u00eds desconocido Procedencia: MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":42506,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2592,2595],"anho":[2713],"pais":[2717],"class_list":["post-42505","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-comercio","cat-objetos-embalaje","anho-s-f","pais-pais-desconocido"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/42505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=42505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/42506"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=42505"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=42505"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=42505"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=42505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}