{"id":39723,"date":"2024-09-09T13:45:04","date_gmt":"2024-09-09T19:45:04","guid":{"rendered":"https:\/\/elmodo.mx\/objeto\/tricofero-de-barry-tratamiento-capilar\/"},"modified":"2024-12-04T17:35:37","modified_gmt":"2024-12-04T23:35:37","slug":"tricofero-de-barry-tratamiento-capilar","status":"publish","type":"objeto","link":"https:\/\/elmodo.mx\/en\/objeto\/tricofero-de-barry-tratamiento-capilar\/","title":{"rendered":"Tricofero De Barry. Tratamiento Capilar"},"content":{"rendered":"<section class=\"extracto\">\n<p><b>Productor Autor:<\/b> Lanman &#038; Kemp-Barclay &#038; Co De M\u00e9xico<\/p>\n<p><b>A\u00f1o:<\/b> S\/F<\/p>\n<p><b>Pa\u00eds:<\/b> M\u00e9xico<\/p>\n<p><b>Procedencia:<\/b> MODO, Museo del Objeto del Objeto.<\/p>\n<p>\u00a0<\/p>\n<section class=\"extracto-oculto\">\n<h3>Caracter\u00edsticas<\/h3>\n<p><b>Ancho:<\/b> <\/p>\n<p><b>Largo Alto:<\/b> <\/p>\n<p><b>Profundidad:<\/b> <\/p>\n<p><b>Material predominante:<\/b> Vidrio<\/p>\n<p>\u00a0<\/p>\n<p><b>Colecci\u00f3n:<\/b> Apariencia<\/p>\n<p><b>Categor\u00eda:<\/b> Cosm\u00e9ticos<\/p>\n<p><b>ID Inventario:<\/b> 8715<\/p>\n<\/section>\n<p>\u00a0<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Productor Autor: Lanman &#038; Kemp-Barclay &#038; Co De M\u00e9xico A\u00f1o: S\/F Pa\u00eds: M\u00e9xico Procedencia: MODO, Museo del Objeto del Objeto.<\/p>\n","protected":false},"featured_media":36659,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_members_access_role":[],"_members_access_error":""},"cat-objetos":[2587,2588],"anho":[2713],"pais":[2714],"class_list":["post-39723","objeto","type-objeto","status-publish","format-standard","has-post-thumbnail","hentry","cat-objetos-apariencia","cat-objetos-cosmeticos","anho-s-f","pais-mexico"],"_links":{"self":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto\/39723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/objeto"}],"about":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/types\/objeto"}],"replies":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/comments?post=39723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media\/36659"}],"wp:attachment":[{"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/media?parent=39723"}],"wp:term":[{"taxonomy":"cat-objetos","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/cat-objetos?post=39723"},{"taxonomy":"anho","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/anho?post=39723"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/elmodo.mx\/en\/wp-json\/wp\/v2\/pais?post=39723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}